{"id":415,"count":2,"description":"","link":"https:\/\/b-logos.sementesdoverbo.org\/pt_br\/course-category\/1-3-mt-zd-comunidades-novas-e-vida-religiosas\/","name":"1-3-mt-zd Comunidades novas e vida religiosas","slug":"1-3-mt-zd-comunidades-novas-e-vida-religiosas","taxonomy":"ld_course_category","parent":172,"meta":[],"z_taxonomy_image_url":"https:\/\/b-logos.sementesdoverbo.org\/wp-content\/plugins\/categories-images\/assets\/images\/placeholder.png","_links":{"self":[{"href":"https:\/\/b-logos.sementesdoverbo.org\/pt_br\/wp-json\/wp\/v2\/ld_course_category\/415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/b-logos.sementesdoverbo.org\/pt_br\/wp-json\/wp\/v2\/ld_course_category"}],"about":[{"href":"https:\/\/b-logos.sementesdoverbo.org\/pt_br\/wp-json\/wp\/v2\/taxonomies\/ld_course_category"}],"up":[{"embeddable":true,"href":"https:\/\/b-logos.sementesdoverbo.org\/pt_br\/wp-json\/wp\/v2\/ld_course_category\/172"}],"wp:post_type":[{"href":"https:\/\/b-logos.sementesdoverbo.org\/pt_br\/wp-json\/wp\/v2\/sfwd-courses?ld_course_category=415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}